{"id":119,"count":1,"description":"","link":"https:\/\/www.premierdentalwaco.com\/blog\/tag\/adult-braces\/","name":"adult braces","slug":"adult-braces","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.premierdentalwaco.com\/blog\/wp-json\/wp\/v2\/tags\/119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.premierdentalwaco.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.premierdentalwaco.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.premierdentalwaco.com\/blog\/wp-json\/wp\/v2\/posts?tags=119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}